{"id":4612,"date":"2025-11-11T09:37:13","date_gmt":"2025-11-11T08:37:13","guid":{"rendered":"https:\/\/www.wiegandsystem.de\/cms\/de\/?page_id=4612"},"modified":"2026-02-04T11:00:53","modified_gmt":"2026-02-04T10:00:53","slug":"visitenwagen-light","status":"publish","type":"page","link":"https:\/\/www.wiegandsystem.de\/cms\/de\/loesungen\/flexline-wagen_alt\/visitenwagen-light\/","title":{"rendered":"Visitenwagen LIGHT"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":687,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-4612","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Visitenwagen LIGHT - Wiegand System GmbH<\/title>\n<meta name=\"description\" content=\"Visitenwagen LIGHT - Wertvolle Entlastung durch intelligente L\u00f6sungen: Medikamentenmanagement und Krankenhauslogistik\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.wiegandsystem.de\/cms\/de\/loesungen\/flexline-wagen_alt\/visitenwagen-light\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Visitenwagen LIGHT - Wiegand System GmbH\" \/>\n<meta property=\"og:description\" content=\"Visitenwagen LIGHT - Wertvolle Entlastung durch intelligente L\u00f6sungen: Medikamentenmanagement und Krankenhauslogistik\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.wiegandsystem.de\/cms\/de\/loesungen\/flexline-wagen_alt\/visitenwagen-light\/\" \/>\n<meta property=\"og:site_name\" content=\"Wiegand System GmbH\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-04T10:00:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.wiegandsystem.de\/cms\/de\/wp-content\/uploads\/2025\/04\/wiegand-systems-og-image-v2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.wiegandsystem.de\\\/cms\\\/de\\\/loesungen\\\/flexline-wagen_alt\\\/visitenwagen-light\\\/\",\"url\":\"https:\\\/\\\/www.wiegandsystem.de\\\/cms\\\/de\\\/loesungen\\\/flexline-wagen_alt\\\/visitenwagen-light\\\/\",\"name\":\"Visitenwagen LIGHT - Wiegand System GmbH\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.wiegandsystem.de\\\/cms\\\/de\\\/#website\"},\"datePublished\":\"2025-11-11T08:37:13+00:00\",\"dateModified\":\"2026-02-04T10:00:53+00:00\",\"description\":\"Visitenwagen LIGHT - Wertvolle Entlastung durch intelligente L\u00f6sungen: Medikamentenmanagement und Krankenhauslogistik\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.wiegandsystem.de\\\/cms\\\/de\\\/loesungen\\\/flexline-wagen_alt\\\/visitenwagen-light\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.wiegandsystem.de\\\/cms\\\/de\\\/loesungen\\\/flexline-wagen_alt\\\/visitenwagen-light\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.wiegandsystem.de\\\/cms\\\/de\\\/loesungen\\\/flexline-wagen_alt\\\/visitenwagen-light\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.wiegandsystem.de\\\/cms\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L\u00f6sungen\",\"item\":\"https:\\\/\\\/www.wiegandsystem.de\\\/cms\\\/de\\\/loesungen\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Wagen-ALT\",\"item\":\"https:\\\/\\\/www.wiegandsystem.de\\\/cms\\\/de\\\/?page_id=687\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Visitenwagen LIGHT\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.wiegandsystem.de\\\/cms\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.wiegandsystem.de\\\/cms\\\/de\\\/\",\"name\":\"Wiegand System GmbH\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.wiegandsystem.de\\\/cms\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.wiegandsystem.de\\\/cms\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.wiegandsystem.de\\\/cms\\\/de\\\/#organization\",\"name\":\"Wiegand System GmbH\",\"url\":\"https:\\\/\\\/www.wiegandsystem.de\\\/cms\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.wiegandsystem.de\\\/cms\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.wiegandsystem.de\\\/cms\\\/de\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/wiegand-systems-yoast-org-logo-v2.png\",\"contentUrl\":\"https:\\\/\\\/www.wiegandsystem.de\\\/cms\\\/de\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/wiegand-systems-yoast-org-logo-v2.png\",\"width\":696,\"height\":696,\"caption\":\"Wiegand System GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/www.wiegandsystem.de\\\/cms\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Visitenwagen LIGHT - Wiegand System GmbH","description":"Visitenwagen LIGHT - Wertvolle Entlastung durch intelligente L\u00f6sungen: Medikamentenmanagement und Krankenhauslogistik","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.wiegandsystem.de\/cms\/de\/loesungen\/flexline-wagen_alt\/visitenwagen-light\/","og_locale":"de_DE","og_type":"article","og_title":"Visitenwagen LIGHT - Wiegand System GmbH","og_description":"Visitenwagen LIGHT - Wertvolle Entlastung durch intelligente L\u00f6sungen: Medikamentenmanagement und Krankenhauslogistik","og_url":"https:\/\/www.wiegandsystem.de\/cms\/de\/loesungen\/flexline-wagen_alt\/visitenwagen-light\/","og_site_name":"Wiegand System GmbH","article_modified_time":"2026-02-04T10:00:53+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.wiegandsystem.de\/cms\/de\/wp-content\/uploads\/2025\/04\/wiegand-systems-og-image-v2.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.wiegandsystem.de\/cms\/de\/loesungen\/flexline-wagen_alt\/visitenwagen-light\/","url":"https:\/\/www.wiegandsystem.de\/cms\/de\/loesungen\/flexline-wagen_alt\/visitenwagen-light\/","name":"Visitenwagen LIGHT - Wiegand System GmbH","isPartOf":{"@id":"https:\/\/www.wiegandsystem.de\/cms\/de\/#website"},"datePublished":"2025-11-11T08:37:13+00:00","dateModified":"2026-02-04T10:00:53+00:00","description":"Visitenwagen LIGHT - Wertvolle Entlastung durch intelligente L\u00f6sungen: Medikamentenmanagement und Krankenhauslogistik","breadcrumb":{"@id":"https:\/\/www.wiegandsystem.de\/cms\/de\/loesungen\/flexline-wagen_alt\/visitenwagen-light\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.wiegandsystem.de\/cms\/de\/loesungen\/flexline-wagen_alt\/visitenwagen-light\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.wiegandsystem.de\/cms\/de\/loesungen\/flexline-wagen_alt\/visitenwagen-light\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.wiegandsystem.de\/cms\/de\/"},{"@type":"ListItem","position":2,"name":"L\u00f6sungen","item":"https:\/\/www.wiegandsystem.de\/cms\/de\/loesungen\/"},{"@type":"ListItem","position":3,"name":"Wagen-ALT","item":"https:\/\/www.wiegandsystem.de\/cms\/de\/?page_id=687"},{"@type":"ListItem","position":4,"name":"Visitenwagen LIGHT"}]},{"@type":"WebSite","@id":"https:\/\/www.wiegandsystem.de\/cms\/de\/#website","url":"https:\/\/www.wiegandsystem.de\/cms\/de\/","name":"Wiegand System GmbH","description":"","publisher":{"@id":"https:\/\/www.wiegandsystem.de\/cms\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.wiegandsystem.de\/cms\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.wiegandsystem.de\/cms\/de\/#organization","name":"Wiegand System GmbH","url":"https:\/\/www.wiegandsystem.de\/cms\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.wiegandsystem.de\/cms\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.wiegandsystem.de\/cms\/de\/wp-content\/uploads\/2025\/04\/wiegand-systems-yoast-org-logo-v2.png","contentUrl":"https:\/\/www.wiegandsystem.de\/cms\/de\/wp-content\/uploads\/2025\/04\/wiegand-systems-yoast-org-logo-v2.png","width":696,"height":696,"caption":"Wiegand System GmbH"},"image":{"@id":"https:\/\/www.wiegandsystem.de\/cms\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.wiegandsystem.de\/cms\/de\/wp-json\/wp\/v2\/pages\/4612","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.wiegandsystem.de\/cms\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.wiegandsystem.de\/cms\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.wiegandsystem.de\/cms\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.wiegandsystem.de\/cms\/de\/wp-json\/wp\/v2\/comments?post=4612"}],"version-history":[{"count":4,"href":"https:\/\/www.wiegandsystem.de\/cms\/de\/wp-json\/wp\/v2\/pages\/4612\/revisions"}],"predecessor-version":[{"id":4810,"href":"https:\/\/www.wiegandsystem.de\/cms\/de\/wp-json\/wp\/v2\/pages\/4612\/revisions\/4810"}],"up":[{"embeddable":true,"href":"https:\/\/www.wiegandsystem.de\/cms\/de\/wp-json\/wp\/v2\/pages\/687"}],"wp:attachment":[{"href":"https:\/\/www.wiegandsystem.de\/cms\/de\/wp-json\/wp\/v2\/media?parent=4612"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}